{"id":205583,"date":"2026-09-01T15:33:06","date_gmt":"2026-09-01T13:33:06","guid":{"rendered":"https:\/\/www.bordeaux-neurocampus.fr\/les-rendez-vous-de-lanr\/"},"modified":"2026-09-01T20:35:55","modified_gmt":"2026-09-01T18:35:55","slug":"les-rendez-vous-de-lanr","status":"publish","type":"post","link":"https:\/\/www.bordeaux-neurocampus.fr\/en\/les-rendez-vous-de-lanr\/","title":{"rendered":"Les rendez-vous de l&#8217;ANR"},"content":{"rendered":"<p>L&#8217;ANR vient \u00e0 la rencontre des communaut\u00e9s scientifiques du site bordelais pour accompagner la publication de son plan d&#8217;action 2027 et le lancement de l&#8217;\u00e9dition 2027 de l&#8217;appel \u00e0 projets g\u00e9n\u00e9rique.<\/p>\n<p>Cette rencontre permet de proposer des temps d\u2019\u00e9changes avec les porteurs de projets et les acteurs institutionnels de la recherche, elle est l\u2019occasion de r\u00e9pondre aux interrogations des porteurs de projets et de leurs services supports, de clarifier les points sur les modalit\u00e9s de soumission, le processus de s\u00e9lection et d&#8217;\u00e9valuation et les \u00e9volutions de l&#8217;\u00e9dition 2027.<\/p>\n<p>La session sur le site de Bordeaux se tiendra :<\/p>\n<p><strong>Mercredi 16 septembre 2026\u00a0<\/strong><\/p>\n<p><strong>Campus de l&#8217;Universit\u00e9 de Bordeaux &#8211; Domaine Haut Carr\u00e9 &#8211; Auditorium AGORA\u00a0<\/strong><\/p>\n<p><strong>43 rue Pierre Noailles &#8211; 33400 Talence<\/strong><\/p>\n<h3>Inscription<\/h3>\n<p><strong>Inscription obligatoire via<\/strong><\/p>\n<p><a href=\"https:\/\/framaforms.org\/inscription-les-rendez-vous-de-lanr-2026-session-bordeaux-16-septembre-2026-1784207843\">https:\/\/framaforms.org\/inscription-les-rendez-vous-de-lanr-2026-session-bordeaux-16-septembre-2026-1784207843<\/a><\/p>\n<h3>Programme<\/h3>\n<ul>\n<li>Matin : 9h30 &#8211; 13h00 &#8211; Pl\u00e9ni\u00e8re<\/li>\n<\/ul>\n<p>Pr\u00e9sentation du plan d\u2019action 2027, avec un focus sur l\u2019AAPG et ses \u00e9volutions.<\/p>\n<ul>\n<li>Apr\u00e8s-midi : 14h15 &#8211; 16 h15 &#8211; 2 ateliers en parall\u00e8le<\/li>\n<\/ul>\n<p>&#8211; Atelier 1 : Financements ANR &#8211; Quels dispositifs pour accompagner les partenariats avec des organisations priv\u00e9es ?<\/p>\n<p>&#8211; Atelier 2 : Forfaitisation des aides &#8211; Dispositifs concern\u00e9s et mise en \u0153uvre<\/p>\n<h3>Contact<\/h3>\n<p>anr@u-bordeaux.fr<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercredi 16 septembre 2026 \u00e0 l&#8217;Agora du Haut-Carr\u00e9<\/p>\n","protected":false},"author":108,"featured_media":137101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-205583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenement-en"],"_links":{"self":[{"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/posts\/205583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/comments?post=205583"}],"version-history":[{"count":1,"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/posts\/205583\/revisions"}],"predecessor-version":[{"id":205602,"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/posts\/205583\/revisions\/205602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/media\/137101"}],"wp:attachment":[{"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/media?parent=205583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/categories?post=205583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bordeaux-neurocampus.fr\/en\/wp-json\/wp\/v2\/tags?post=205583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}